{"id":10878,"date":"2026-09-01T15:52:58","date_gmt":"2026-09-01T21:52:58","guid":{"rendered":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/"},"modified":"2026-09-01T15:53:01","modified_gmt":"2026-09-01T21:53:01","slug":"comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino","status":"publish","type":"post","link":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/","title":{"rendered":"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino)"},"content":{"rendered":"<p><\/p>\n<p>Comer mejor no significa s\u00f3lo elegir frutas y verduras con m\u00e1s frecuencia. Tambi\u00e9n puede ser importante variar lo que aportamos tanto como sea posible. De esta idea naci\u00f3 el llamado \u201creto 30 plantas a la semana\u201d, una tendencia alimentaria que invita a consumir al menos 30 alimentos diferentes de origen vegetal durante siete d\u00edas.<\/p>\n<p>Podr\u00eda parecer una simple tendencia nacida en las redes sociales, pero detr\u00e1s de esta cifra se esconden importantes investigaciones cient\u00edficas sobre la microbiota intestinal.<\/p>\n<h2>\u00bfQu\u00e9 es el desaf\u00edo de las 30 plantas?<\/h2>\n<p>La regla es muy simple: en una semana debes intentar comer 30 tipos diferentes de alimentos vegetales. No significa comer 30 porciones de verduras o incluso consumir grandes cantidades de comida. El objetivo es aumentar la variedad de la dieta.<\/p>\n<p>El recuento puede incluir frutas y verduras, pero tambi\u00e9n legumbres, cereales integrales, frutos secos, semillas, hierbas arom\u00e1ticas y especias. En la pr\u00e1ctica, un pu\u00f1ado de frutos secos puede sumar una entrada, al igual que una raci\u00f3n de garbanzos, una ensalada con r\u00facula, un plato de avena o una fruta diferente a la consumida el d\u00eda anterior.<\/p>\n<p>La idea se ha vuelto particularmente popular porque convierte la variedad de alimentos en una especie de juego: en lugar de contar calor\u00edas o eliminar alimentos, simplemente intentas agregar nuevas plantas a tu semana.<\/p>\n<h2>De la investigaci\u00f3n de la microbiota a las redes sociales<\/h2>\n<p>El origen del famoso n\u00famero 30 se remonta a<em>&#8216;Proyecto intestinal americano<\/em>uno de los mayores proyectos de investigaci\u00f3n sobre el microbioma humano, cuyos resultados se publicaron en 2018 en la revista cient\u00edfica <em>mSistemas<\/em>.<\/p>\n<p>Los investigadores analizaron las muestras y los h\u00e1bitos alimentarios de m\u00e1s de 10.000 participantes, observando tambi\u00e9n la relaci\u00f3n entre la variedad de alimentos vegetales consumidos y la composici\u00f3n de la microbiota intestinal. Las personas que informaron comer m\u00e1s de 30 tipos diferentes de plantas por semana ten\u00edan una mayor diversidad microbiana que aquellas que consum\u00edan 10 o menos.<\/p>\n<p>A partir de ese momento, el concepto de \u201c30 plantas por semana\u201d sali\u00f3 del \u00e1mbito de la investigaci\u00f3n y se convirti\u00f3 en un verdadero objetivo alimentario que vale la pena intentar.<\/p>\n<p>La difusi\u00f3n en las redes sociales est\u00e1 bien documentada. En 2025, por ejemplo, ProVeg International cont\u00f3 c\u00f3mo, tras el estreno del documental de Netflix &#8220;<em>Hackea tu salud: los secretos de tu intestino<\/em>\u201c, el tema de las 30 plantas empez\u00f3 a aparecer cada vez m\u00e1s en Instagram, hasta el punto de empujar al autor a probar el desaf\u00edo personalmente.<\/p>\n<p>La tendencia tambi\u00e9n ha llegado al mundo de la alimentaci\u00f3n y la restauraci\u00f3n: en 2025, FoodNavigator describi\u00f3 &#8220;30 plantas por semana&#8221; como una tendencia creciente, respaldada tambi\u00e9n por las cifras de divulgaci\u00f3n alimentaria brit\u00e1nica.<\/p>\n<p>Y el fen\u00f3meno no parece haber terminado, en 2026 el desaf\u00edo se sigue proponiendo a trav\u00e9s de trackers, recetas e iniciativas dedicadas a propuestas plant-based.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF;border: 0;border-radius: 3px;margin: 1px;max-width: 540px;min-width: 326px;padding: 0;width: calc(100% - 2px)\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DTsv8kfCRen\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px\">\n<p>&nbsp;<\/p>\n<div style=\"flex-direction: row;align-items: center\">\n<div style=\"background-color: #f4f4f4;border-radius: 50%;flex-grow: 0;height: 40px;margin-right: 14px;width: 40px\"><\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center\">\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 100px\"><\/div>\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;width: 60px\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0\"><\/div>\n<div style=\"height: 50px;margin: 0 auto 12px;width: 50px\"><\/div>\n<div style=\"padding-top: 8px\">\n<div style=\"color: #3897f0;font-family: Arial,sans-serif;font-size: 14px;font-style: normal;font-weight: 550;line-height: 18px\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0\"><\/div>\n<div style=\"flex-direction: row;margin-bottom: 14px;align-items: center\">\n<div>\n<div style=\"background-color: #f4f4f4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<div style=\"background-color: #f4f4f4;height: 12.5px;width: 12.5px;flex-grow: 0;margin-right: 14px;margin-left: 2px\"><\/div>\n<div style=\"background-color: #f4f4f4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px\">\n<div style=\"background-color: #f4f4f4;border-radius: 50%;flex-grow: 0;height: 20px;width: 20px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 2px solid transparent;border-left: 6px solid #f4f4f4;border-bottom: 2px solid transparent\"><\/div>\n<\/div>\n<div style=\"margin-left: auto\">\n<div style=\"width: 0px;border-top: 8px solid #F4F4F4;border-right: 8px solid transparent\"><\/div>\n<div style=\"background-color: #f4f4f4;flex-grow: 0;height: 12px;width: 16px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 8px solid #F4F4F4;border-left: 8px solid transparent\"><\/div>\n<\/div>\n<\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center;margin-bottom: 24px\">\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 224px\"><\/div>\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;width: 144px\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd;font-family: Arial,sans-serif;font-size: 14px;line-height: 17px;margin-bottom: 0;margin-top: 8px;overflow: hidden;padding: 8px 0 7px;text-align: center\">Una publicaci\u00f3n compartida por Caldwell B. Esselstyn, Jr., MD (@dresselstyn)<\/p>\n<\/div>\n<\/blockquote>\n<h2>Por qu\u00e9 la variedad podr\u00eda ser importante para la microbiota<\/h2>\n<p>Nuestros intestinos albergan una enorme comunidad de microorganismos que interact\u00faan continuamente con lo que comemos. De hecho, las diferentes plantas aportan fibras, polifenoles y otras sustancias que pueden ser aprovechadas por los microorganismos intestinales. Por lo tanto, aumentar la variedad de fuentes vegetales significa poner a disposici\u00f3n de la microbiota una gama m\u00e1s amplia de nutrientes y compuestos.<\/p>\n<p>La Iniciativa Microsetta de la Universidad de California en San Diego, que retoma el legado del American Gut Project, explica que en su conjunto de datos, las personas que afirmaron consumir al menos 30 tipos diferentes de plantas por semana ten\u00edan una mayor diversidad de microbiota en comparaci\u00f3n con quienes consum\u00edan menos.<\/p>\n<p>Pero ojo: una mayor diversidad de la microbiota no significa autom\u00e1ticamente una mayor salud y, sobre todo, no significa que exista un umbral m\u00e1s all\u00e1 del cual nuestro intestino se vuelve repentinamente &#8220;sano&#8221;.<\/p>\n<p>En definitiva, el n\u00famero 30 no es un umbral m\u00e1gico. \u00c9ste es precisamente el punto que vale la pena aclarar.<\/p>\n<p>El estudio de 2018 encontr\u00f3 una asociaci\u00f3n entre la variedad de plantas consumidas y las caracter\u00edsticas de la microbiota. No est\u00e1 demostrado que comer exactamente 30 plantas a la semana mejore la salud, ni que 30 sea el n\u00famero m\u00ednimo necesario para tener un intestino sano.<\/p>\n<p>Incluso The Guardian, en un an\u00e1lisis en profundidad publicado en julio de 2026, volvi\u00f3 a poner bajo el microscopio el famoso umbral: seg\u00fan los expertos citados en el art\u00edculo, el n\u00famero 30 es bastante arbitrario. De hecho, la investigaci\u00f3n no compar\u00f3 sistem\u00e1ticamente 10, 20, 30 y 35 plantas para identificar un punto de inflexi\u00f3n preciso.<\/p>\n<p>Luego hay otra limitaci\u00f3n importante: se trata de una investigaci\u00f3n observacional. Las personas que comen una amplia variedad de verduras tambi\u00e9n pueden tener otros h\u00e1bitos asociados con una mejor salud, desde la actividad f\u00edsica hasta el sue\u00f1o y el consumo general de alimentos menos ultraprocesados. Por ello no podemos decir que fue el simple hecho de superar los 30 lo que determin\u00f3 las diferencias observadas.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF;border: 0;border-radius: 3px;margin: 1px;max-width: 540px;min-width: 326px;padding: 0;width: calc(100% - 2px)\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DGOIDABoOAX\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px\">\n<p>&nbsp;<\/p>\n<div style=\"flex-direction: row;align-items: center\">\n<div style=\"background-color: #f4f4f4;border-radius: 50%;flex-grow: 0;height: 40px;margin-right: 14px;width: 40px\"><\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center\">\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 100px\"><\/div>\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;width: 60px\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0\"><\/div>\n<div style=\"height: 50px;margin: 0 auto 12px;width: 50px\"><\/div>\n<div style=\"padding-top: 8px\">\n<div style=\"color: #3897f0;font-family: Arial,sans-serif;font-size: 14px;font-style: normal;font-weight: 550;line-height: 18px\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0\"><\/div>\n<div style=\"flex-direction: row;margin-bottom: 14px;align-items: center\">\n<div>\n<div style=\"background-color: #f4f4f4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<div style=\"background-color: #f4f4f4;height: 12.5px;width: 12.5px;flex-grow: 0;margin-right: 14px;margin-left: 2px\"><\/div>\n<div style=\"background-color: #f4f4f4;border-radius: 50%;height: 12.5px;width: 12.5px\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px\">\n<div style=\"background-color: #f4f4f4;border-radius: 50%;flex-grow: 0;height: 20px;width: 20px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 2px solid transparent;border-left: 6px solid #f4f4f4;border-bottom: 2px solid transparent\"><\/div>\n<\/div>\n<div style=\"margin-left: auto\">\n<div style=\"width: 0px;border-top: 8px solid #F4F4F4;border-right: 8px solid transparent\"><\/div>\n<div style=\"background-color: #f4f4f4;flex-grow: 0;height: 12px;width: 16px\"><\/div>\n<div style=\"width: 0;height: 0;border-top: 8px solid #F4F4F4;border-left: 8px solid transparent\"><\/div>\n<\/div>\n<\/div>\n<div style=\"flex-direction: column;flex-grow: 1;justify-content: center;margin-bottom: 24px\">\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;margin-bottom: 6px;width: 224px\"><\/div>\n<div style=\"background-color: #f4f4f4;border-radius: 4px;flex-grow: 0;height: 14px;width: 144px\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd;font-family: Arial,sans-serif;font-size: 14px;line-height: 17px;margin-bottom: 0;margin-top: 8px;overflow: hidden;padding: 8px 0 7px;text-align: center\">Una publicaci\u00f3n compartida por la Dra. Emily Leeming | Nutrici\u00f3n (@dremilyleeming)<\/p>\n<\/div>\n<\/blockquote>\n<h2>Entonces, \u00bfvale la pena intentarlo?<\/h2>\n<p>S\u00ed, pero sin convertir el n\u00famero en una nueva obsesi\u00f3n alimentaria. El mensaje m\u00e1s interesante del reto no es tanto \u201chay que llegar a los 30\u201d, sino \u201cintenta comer m\u00e1s variedad\u201d.<\/p>\n<p>Si durante la semana comemos siempre las mismas verduras, la misma fruta y los mismos cereales, simplemente podemos intentar cambiar algo. Garbanzos en lugar de jud\u00edas, avena en lugar del cereal habitual, un pu\u00f1ado de frutos secos, pipas de calabaza, una verdura diferente de temporada, unas cuantas hierbas arom\u00e1ticas m\u00e1s.<\/p>\n<p>Incluso sin llegar a los 30, aumentar gradualmente la variedad puede ser una forma sencilla de mejorar la calidad general de su dieta.<\/p>\n<h2>\u00bfQu\u00e9 podemos contar en las 30 plantas?<\/h2>\n<p>No tienes que pensar en 30 platos enormes de ensalada. La lista puede crecer mucho m\u00e1s f\u00e1cilmente de lo que parece:<\/p>\n<p>Ni siquiera necesitas revolucionar tu dieta de la noche a la ma\u00f1ana. Un desayuno con avena, semillas y frutos rojos, una ensalada enriquecida con legumbres y semillas para el almuerzo y una cena con diferentes verduras ya pueden aumentar significativamente el n\u00famero de plantas consumidas a lo largo de la semana.<\/p>\n<p>Fuentes: American Gut Project \/ Iniciativa Microsetta \u2013 Universidad de California en San Diego<\/p>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comer mejor no significa s\u00f3lo elegir frutas y verduras con m\u00e1s frecuencia. Tambi\u00e9n puede ser importante variar lo que aportamos tanto como sea posible. De<\/p>\n","protected":false},"author":1,"featured_media":10879,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[762],"tags":[920,789,9793,3225,2894,914,34,29,2999,406,2817,1713,111,562,2818],"class_list":["post-10878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-bueno","tag-comer","tag-conquistado","tag-diferentes","tag-facil","tag-intestino","tag-las","tag-para","tag-plantas","tag-puede","tag-redes","tag-reto","tag-semana","tag-ser","tag-sociales","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino) - Consejos - Santa Catarina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino) - Consejos - Santa Catarina\" \/>\n<meta property=\"og:description\" content=\"Comer mejor no significa s\u00f3lo elegir frutas y verduras con m\u00e1s frecuencia. Tambi\u00e9n puede ser importante variar lo que aportamos tanto como sea posible. De\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Catarina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/stacatarinagob\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T21:52:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T21:53:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@stacatarinagob\" \/>\n<meta name=\"twitter:site\" content=\"@stacatarinagob\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/\"},\"author\":{\"name\":\"Pedro Mart\u00ednez\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a\"},\"headline\":\"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino)\",\"datePublished\":\"2026-09-01T21:52:58+00:00\",\"dateModified\":\"2026-09-01T21:53:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/\"},\"wordCount\":1117,\"publisher\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#organization\"},\"image\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg\",\"keywords\":[\"bueno\",\"comer\",\"conquistado\",\"diferentes\",\"f\u00e1cil\",\"intestino\",\"Las\",\"para\",\"plantas\",\"puede\",\"redes\",\"reto\",\"semana\",\"ser\",\"sociales\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/\",\"name\":\"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino) - Consejos - Santa Catarina\",\"isPartOf\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg\",\"datePublished\":\"2026-09-01T21:52:58+00:00\",\"dateModified\":\"2026-09-01T21:53:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg\",\"contentUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"mangiare frutta verdura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/stacatarina.mx\/consejos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#website\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/\",\"name\":\"Santa Catarina\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stacatarina.mx\/consejos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#organization\",\"name\":\"Santa Catarina\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png\",\"contentUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png\",\"width\":512,\"height\":512,\"caption\":\"Santa Catarina\"},\"image\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/stacatarinagob\/\",\"https:\/\/x.com\/stacatarinagob\",\"https:\/\/www.instagram.com\/stacatarinagob\/\",\"https:\/\/www.youtube.com\/channel\/UCK-6cQJL_904665N1_nLTWw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a\",\"name\":\"Pedro Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg\",\"contentUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg\",\"caption\":\"Pedro Mart\u00ednez\"},\"description\":\"Hola, soy Pedro Mart\u00ednez, redactor jefe del sitio oficial del ayuntamiento de Santa Catarina, en M\u00e9xico. Con m\u00e1s de diez a\u00f1os de experiencia en el periodismo local, tengo una pasi\u00f3n por la investigaci\u00f3n y la difusi\u00f3n de informaci\u00f3n que valoriza nuestra hermosa comunidad. Mi compromiso es hacer de Santa Catarina una referencia en materia de transparencia y comunicaci\u00f3n municipal.\",\"sameAs\":[\"https:\/\/stacatarina.mx\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino) - Consejos - Santa Catarina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/","og_locale":"es_MX","og_type":"article","og_title":"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino) - Consejos - Santa Catarina","og_description":"Comer mejor no significa s\u00f3lo elegir frutas y verduras con m\u00e1s frecuencia. Tambi\u00e9n puede ser importante variar lo que aportamos tanto como sea posible. De","og_url":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/","og_site_name":"Santa Catarina","article_publisher":"https:\/\/www.facebook.com\/stacatarinagob\/","article_published_time":"2026-09-01T21:52:58+00:00","article_modified_time":"2026-09-01T21:53:01+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg","type":"image\/jpeg"}],"author":"Pedro Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@stacatarinagob","twitter_site":"@stacatarinagob","twitter_misc":{"Escrito por":"Pedro Mart\u00ednez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#article","isPartOf":{"@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/"},"author":{"name":"Pedro Mart\u00ednez","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a"},"headline":"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino)","datePublished":"2026-09-01T21:52:58+00:00","dateModified":"2026-09-01T21:53:01+00:00","mainEntityOfPage":{"@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/"},"wordCount":1117,"publisher":{"@id":"https:\/\/stacatarina.mx\/consejos\/#organization"},"image":{"@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage"},"thumbnailUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg","keywords":["bueno","comer","conquistado","diferentes","f\u00e1cil","intestino","Las","para","plantas","puede","redes","reto","semana","ser","sociales"],"articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/","url":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/","name":"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino) - Consejos - Santa Catarina","isPartOf":{"@id":"https:\/\/stacatarina.mx\/consejos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage"},"image":{"@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage"},"thumbnailUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg","datePublished":"2026-09-01T21:52:58+00:00","dateModified":"2026-09-01T21:53:01+00:00","breadcrumb":{"@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#primaryimage","url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg","contentUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2026\/09\/Comer-30-plantas-diferentes-a-la-semana-el-reto-facil.jpg","width":1500,"height":1000,"caption":"mangiare frutta verdura"},{"@type":"BreadcrumbList","@id":"https:\/\/stacatarina.mx\/consejos\/comer-30-plantas-diferentes-a-la-semana-el-reto-facil-que-ha-conquistado-las-redes-sociales-y-que-puede-ser-bueno-para-tu-intestino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/stacatarina.mx\/consejos\/"},{"@type":"ListItem","position":2,"name":"Comer 30 plantas diferentes a la semana: el reto f\u00e1cil que ha conquistado las redes sociales (y que puede ser bueno para tu intestino)"}]},{"@type":"WebSite","@id":"https:\/\/stacatarina.mx\/consejos\/#website","url":"https:\/\/stacatarina.mx\/consejos\/","name":"Santa Catarina","description":"","publisher":{"@id":"https:\/\/stacatarina.mx\/consejos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stacatarina.mx\/consejos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/stacatarina.mx\/consejos\/#organization","name":"Santa Catarina","url":"https:\/\/stacatarina.mx\/consejos\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/","url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png","contentUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png","width":512,"height":512,"caption":"Santa Catarina"},"image":{"@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/stacatarinagob\/","https:\/\/x.com\/stacatarinagob","https:\/\/www.instagram.com\/stacatarinagob\/","https:\/\/www.youtube.com\/channel\/UCK-6cQJL_904665N1_nLTWw"]},{"@type":"Person","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a","name":"Pedro Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/image\/","url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg","contentUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg","caption":"Pedro Mart\u00ednez"},"description":"Hola, soy Pedro Mart\u00ednez, redactor jefe del sitio oficial del ayuntamiento de Santa Catarina, en M\u00e9xico. Con m\u00e1s de diez a\u00f1os de experiencia en el periodismo local, tengo una pasi\u00f3n por la investigaci\u00f3n y la difusi\u00f3n de informaci\u00f3n que valoriza nuestra hermosa comunidad. Mi compromiso es hacer de Santa Catarina una referencia en materia de transparencia y comunicaci\u00f3n municipal.","sameAs":["https:\/\/stacatarina.mx\/"]}]}},"_links":{"self":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts\/10878"}],"collection":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/comments?post=10878"}],"version-history":[{"count":1,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts\/10878\/revisions"}],"predecessor-version":[{"id":10880,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts\/10878\/revisions\/10880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/media\/10879"}],"wp:attachment":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/media?parent=10878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/categories?post=10878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/tags?post=10878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}