{"id":3443,"date":"2025-04-07T12:48:39","date_gmt":"2025-04-07T18:48:39","guid":{"rendered":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/"},"modified":"2025-04-07T12:48:40","modified_gmt":"2025-04-07T18:48:40","slug":"detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta","status":"publish","type":"post","link":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/","title":{"rendered":"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta)"},"content":{"rendered":"<p class=\"single-abstract\">\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tDetente a la violencia obst\u00e9trica y al derecho de elegir si la nueva ley de Portugal es la primera en Europa que da a luz.\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<div class=\"daily-video\" style=\"display: none;\"><\/div>\n<div class=\"wrapper-player\" style=\"display: none; margin-bottom: 15px;\">\n<div id=\"daily-player\" style=\"position: relative; max-width: 100%;\" class=\"video-content\"><\/div>\n<\/p><\/div>\n<div class=\"image-wrapper featured-image no-lazy\" id=\"featured-image\"><\/div>\n<p>Hablamos de diez veces, anegonando alguna forma de regulaci\u00f3n que puede poner fin al acoso y las humillaciones en la sala de partos. A\u00fan as\u00ed, la violencia obst\u00e9trica y ginecol\u00f3gica siempre est\u00e1 ah\u00ed y todav\u00eda se habla muy poco.<\/p>\n<p>De hecho, no es una coincidencia que en 2014, la Organizaci\u00f3n Mundial de la Salud (OMS) haya publicado una declaraci\u00f3n para la prevenci\u00f3n y la eliminaci\u00f3n del abuso y la falta de respeto durante la asistencia del parto en las instalaciones hospitalarias, en las que los tipos de tratamientos &#8220;irrespetuosos y abusivos&#8221; se enumeran hacia las mujeres durante el parto. Sin embargo, en 2018, las recomendaciones de la OMS sobre asistencia para &#8220;una experiencia de parto positiva&#8221; proporcionaron pautas a los pa\u00edses de la comunidad internacional basadas en la protecci\u00f3n y el respeto de los derechos humanos.<\/p>\n<aside style=\"margin: 8px auto; text-align: center; display: block; clear: both;\">\n<div id=\"gpt-passback\">\n<\/div>\n<\/aside>\n<p>Pero no es suficiente y es necesario ir m\u00e1s all\u00e1. En <strong>Portugal<\/strong> Se da un peque\u00f1o paso adelante y el gobierno emite una nueva ley que tiene como objetivo proteger a todas las mujeres embarazadas de posibles actos de violencia obst\u00e9trica &#8220;por&#8221;<em>Defiende la integridad f\u00edsica, ps\u00edquica y emocional de quienes viven la maternidad, garantizando asistencia basada en el consentimiento informado, el respeto por la dignidad y el acceso a informaci\u00f3n clara y comprensible.<\/em>&#8220;.<\/p>\n<blockquote>\n<p>Los derechos a la preconcepci\u00f3n, la procreaci\u00f3n m\u00e9dicamente asistida, el embarazo, el embarazo, el parto, el parto y el posparto &#8220;de las mujeres&#8221;, a trav\u00e9s de la creaci\u00f3n de medidas y la protecci\u00f3n contra la violencia obst\u00e9trica, como se indica en el Di\u00e1rio da Rep\u00fablica, est\u00e1 en juego.<\/p>\n<\/blockquote>\n<h2>La nueva ley de Portugal<\/h2>\n<blockquote>\n<p>La nueva ley define la violencia obst\u00e9trica A &#8220;<em>Cualquier acto u omisi\u00f3n de un profesional de la salud que, en el contexto de la salud sexual y reproductiva, provoca da\u00f1os f\u00edsicos o psicol\u00f3gicos, limita la autonom\u00eda de la decisi\u00f3n o implica la deshumanizaci\u00f3n o los tratamientos degradantes<\/em>&#8220;.<\/p>\n<\/blockquote>\n<p>Estos tambi\u00e9n incluyen actitudes verbales, pr\u00e1cticas m\u00e9dicas realizadas sin consentimiento expl\u00edcito, falta de informaci\u00f3n o uso excesivo de intervenciones sin motivaci\u00f3n cl\u00ednica.<\/p>\n<p>De ahora en adelante, todos los centros de salud p\u00fablicos y privados en Portugal que ayudan al nacimiento deber\u00e1n exhibir <strong>Signos de informaci\u00f3n con la lista de los derechos de los dioses y los m\u00e9todos para informar cualquier abuso. <\/strong>Adem\u00e1s, los pacientes pueden ir acompa\u00f1ados de una persona de confianza durante todas las fases de asistencia, incluidos ex\u00e1menes invasivos o situaciones de emergencia, siempre que no haya riesgos cl\u00ednicos documentados.<\/p>\n<p>Adem\u00e1s, cada mujer embarazada puede hacer un &#8220;plan de nacimiento&#8221;, en el que habr\u00e1 indicado sus preferencias sobre la analgesia, el parto, el contacto de la piel, la lactancia materna y m\u00e1s.<\/p>\n<p>La ley proh\u00edbe expl\u00edcitamente pr\u00e1cticas sistem\u00e1ticas como:<strong><br \/>\n<\/strong><\/p>\n<aside style=\"margin: 8px auto; display: flex; justify-content: center; min-height: 251px;\">\n<div id=\"div-gpt-ad-MPU_Bottom_1\" style=\"min-width: 300px; min-height: 252px;\">\n<\/div>\n<\/aside>\n<p><strong>Amamantamiento<\/strong><\/p>\n<p>Un gran punto de inflexi\u00f3n tambi\u00e9n Art\u00edculo 15 que reconoce a la mujer embarazada <strong>derecho a elegir libremente si y c\u00f3mo amamantar<\/strong>.<\/p>\n<blockquote>\n<p>El derecho a la lactancia debe ser respetado y protegido, para que las madres puedan hacerlo, y debe ser alentada, pero no forzada, a la lactancia, se lee.<\/p>\n<\/blockquote>\n<p>El texto de la ley subraya que la promoci\u00f3n de la lactancia materna no debe traducirse en presi\u00f3n psicol\u00f3gica o juicios morales hacia aquellos que optan por alternativas como la leche artificial. De hecho, la &#8220;lactancia materna forzada&#8221; tambi\u00e9n se encuentra dentro de la definici\u00f3n de violencia obst\u00e9trica, sin tener en cuenta las opciones f\u00edsicas, psicol\u00f3gicas o informadas de la madre.<\/p>\n<p>Los hospitales que violan estas indicaciones pueden ser sancionados econ\u00f3micamente. Para los profesionales involucrados, los procedimientos disciplinarios est\u00e1n previstos.<\/p>\n<p>\u00bfNo quieres perder nuestras noticias?<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detente a la violencia obst\u00e9trica y al derecho de elegir si la nueva ley de Portugal es la primera en Europa que da a luz.<\/p>\n","protected":false},"author":1,"featured_media":3444,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[762],"tags":[15,4367,110,1015,2233,272,4368,3934,1113,705],"class_list":["post-3443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-como","tag-detente","tag-esta","tag-europa","tag-ley","tag-nueva","tag-obstetrica","tag-portugal","tag-primera","tag-violencia","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta) - Consejos - Santa Catarina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta) - Consejos - Santa Catarina\" \/>\n<meta property=\"og:description\" content=\"Detente a la violencia obst\u00e9trica y al derecho de elegir si la nueva ley de Portugal es la primera en Europa que da a luz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Catarina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/stacatarinagob\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-07T18:48:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-07T18:48:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@stacatarinagob\" \/>\n<meta name=\"twitter:site\" content=\"@stacatarinagob\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/\"},\"author\":{\"name\":\"Pedro Mart\u00ednez\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a\"},\"headline\":\"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta)\",\"datePublished\":\"2025-04-07T18:48:39+00:00\",\"dateModified\":\"2025-04-07T18:48:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/\"},\"wordCount\":687,\"publisher\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#organization\"},\"image\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg\",\"keywords\":[\"c\u00f3mo\",\"Detente\",\"esta\",\"Europa\",\"ley\",\"nueva\",\"obst\u00e9trica\",\"Portugal\",\"primera\",\"violencia\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/\",\"name\":\"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta) - Consejos - Santa Catarina\",\"isPartOf\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg\",\"datePublished\":\"2025-04-07T18:48:39+00:00\",\"dateModified\":\"2025-04-07T18:48:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg\",\"contentUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"donna parto partorire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/stacatarina.mx\/consejos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#website\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/\",\"name\":\"Santa Catarina\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stacatarina.mx\/consejos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#organization\",\"name\":\"Santa Catarina\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png\",\"contentUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png\",\"width\":512,\"height\":512,\"caption\":\"Santa Catarina\"},\"image\":{\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/stacatarinagob\/\",\"https:\/\/x.com\/stacatarinagob\",\"https:\/\/www.instagram.com\/stacatarinagob\/\",\"https:\/\/www.youtube.com\/channel\/UCK-6cQJL_904665N1_nLTWw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a\",\"name\":\"Pedro Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg\",\"contentUrl\":\"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg\",\"caption\":\"Pedro Mart\u00ednez\"},\"description\":\"Hola, soy Pedro Mart\u00ednez, redactor jefe del sitio oficial del ayuntamiento de Santa Catarina, en M\u00e9xico. Con m\u00e1s de diez a\u00f1os de experiencia en el periodismo local, tengo una pasi\u00f3n por la investigaci\u00f3n y la difusi\u00f3n de informaci\u00f3n que valoriza nuestra hermosa comunidad. Mi compromiso es hacer de Santa Catarina una referencia en materia de transparencia y comunicaci\u00f3n municipal.\",\"sameAs\":[\"https:\/\/stacatarina.mx\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta) - Consejos - Santa Catarina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/","og_locale":"es_MX","og_type":"article","og_title":"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta) - Consejos - Santa Catarina","og_description":"Detente a la violencia obst\u00e9trica y al derecho de elegir si la nueva ley de Portugal es la primera en Europa que da a luz.","og_url":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/","og_site_name":"Santa Catarina","article_publisher":"https:\/\/www.facebook.com\/stacatarinagob\/","article_published_time":"2025-04-07T18:48:39+00:00","article_modified_time":"2025-04-07T18:48:40+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg","type":"image\/jpeg"}],"author":"Pedro Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@stacatarinagob","twitter_site":"@stacatarinagob","twitter_misc":{"Escrito por":"Pedro Mart\u00ednez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#article","isPartOf":{"@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/"},"author":{"name":"Pedro Mart\u00ednez","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a"},"headline":"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta)","datePublished":"2025-04-07T18:48:39+00:00","dateModified":"2025-04-07T18:48:40+00:00","mainEntityOfPage":{"@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/"},"wordCount":687,"publisher":{"@id":"https:\/\/stacatarina.mx\/consejos\/#organization"},"image":{"@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage"},"thumbnailUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg","keywords":["c\u00f3mo","Detente","esta","Europa","ley","nueva","obst\u00e9trica","Portugal","primera","violencia"],"articleSection":["Salud"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/","url":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/","name":"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta) - Consejos - Santa Catarina","isPartOf":{"@id":"https:\/\/stacatarina.mx\/consejos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage"},"image":{"@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage"},"thumbnailUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg","datePublished":"2025-04-07T18:48:39+00:00","dateModified":"2025-04-07T18:48:40+00:00","breadcrumb":{"@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#primaryimage","url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg","contentUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2025\/04\/Detente-a-la-violencia-obstetrica-la-nueva-ley-de-Portugal.jpg","width":1500,"height":1000,"caption":"donna parto partorire"},{"@type":"BreadcrumbList","@id":"https:\/\/stacatarina.mx\/consejos\/detente-a-la-violencia-obstetrica-la-nueva-ley-de-portugal-es-la-primera-en-europa-como-esta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/stacatarina.mx\/consejos\/"},{"@type":"ListItem","position":2,"name":"Detente a la violencia obst\u00e9trica, la nueva ley de Portugal (es la primera en Europa como esta)"}]},{"@type":"WebSite","@id":"https:\/\/stacatarina.mx\/consejos\/#website","url":"https:\/\/stacatarina.mx\/consejos\/","name":"Santa Catarina","description":"","publisher":{"@id":"https:\/\/stacatarina.mx\/consejos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stacatarina.mx\/consejos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/stacatarina.mx\/consejos\/#organization","name":"Santa Catarina","url":"https:\/\/stacatarina.mx\/consejos\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/","url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png","contentUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/cropped-favicon-1-1.png","width":512,"height":512,"caption":"Santa Catarina"},"image":{"@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/stacatarinagob\/","https:\/\/x.com\/stacatarinagob","https:\/\/www.instagram.com\/stacatarinagob\/","https:\/\/www.youtube.com\/channel\/UCK-6cQJL_904665N1_nLTWw"]},{"@type":"Person","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/0be60adffa8e4c4d0828fdf021450e8a","name":"Pedro Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stacatarina.mx\/consejos\/#\/schema\/person\/image\/","url":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg","contentUrl":"https:\/\/stacatarina.mx\/consejos\/wp-content\/uploads\/2024\/09\/stacatarina.jpg","caption":"Pedro Mart\u00ednez"},"description":"Hola, soy Pedro Mart\u00ednez, redactor jefe del sitio oficial del ayuntamiento de Santa Catarina, en M\u00e9xico. Con m\u00e1s de diez a\u00f1os de experiencia en el periodismo local, tengo una pasi\u00f3n por la investigaci\u00f3n y la difusi\u00f3n de informaci\u00f3n que valoriza nuestra hermosa comunidad. Mi compromiso es hacer de Santa Catarina una referencia en materia de transparencia y comunicaci\u00f3n municipal.","sameAs":["https:\/\/stacatarina.mx\/"]}]}},"_links":{"self":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts\/3443"}],"collection":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/comments?post=3443"}],"version-history":[{"count":1,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts\/3443\/revisions"}],"predecessor-version":[{"id":3445,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/posts\/3443\/revisions\/3445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/media\/3444"}],"wp:attachment":[{"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/media?parent=3443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/categories?post=3443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stacatarina.mx\/consejos\/wp-json\/wp\/v2\/tags?post=3443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}